{"id":22107,"date":"2022-08-31T09:52:27","date_gmt":"2022-08-31T09:52:27","guid":{"rendered":"https:\/\/www.ejuniper.com\/?p=22107"},"modified":"2025-05-08T14:56:21","modified_gmt":"2025-05-08T12:56:21","slug":"juniper-becomes-soc-2-type-ii-certified","status":"publish","type":"post","link":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/","title":{"rendered":"Juniper se certifica en SOC 2 Type II"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Despu\u00e9s de superar la certificaci\u00f3n&nbsp;SOC 2 Type I en la que se&nbsp;<strong>evaluaron 248 controles <\/strong>y tras la <strong>monitorizaci\u00f3n exhaustiva<\/strong> de la auditor\u00eda para verificar el&nbsp;<strong>cumplimiento&nbsp;<\/strong>de los&nbsp;<strong>procesos&nbsp;<\/strong>durante los \u00faltimos meses, <strong>Juniper <\/strong>ha completado con \u00e9xito la&nbsp;<strong>certificaci\u00f3n SOC 2 Type II<\/strong>. La obtenci\u00f3n de esta certificaci\u00f3n <strong>refuerza <\/strong>la promesa de Juniper de mantener los <strong>controles m\u00e1s estrictos,<\/strong> con esta certificaci\u00f3n garantizamos la<strong> seguridad<\/strong>,<strong> disponibilidad<\/strong>, <strong>integridad<\/strong>,<strong> confidencialidad <\/strong>y<strong> privacidad <\/strong>de la informaci\u00f3n de nuestros Clientes.<strong> <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOC 2 Type <\/strong>II es un conjunto de requerimientos <strong>reconocidos internacionalmente<\/strong> y desarrollados por el <strong>Instituto Americano de Contadores P\u00fablicos Certificados<\/strong> (<strong>AICPA<\/strong>). La certificaci\u00f3n engloba la auditor\u00eda de diferentes <strong>controles<\/strong> y <strong>procesos <\/strong>en los que se implique el <strong>almacenamiento<\/strong>, la <strong>manipulaci\u00f3n<\/strong> y la <strong>transmisi\u00f3n <\/strong>de <strong>datos <\/strong>de forma <strong>segura<\/strong>. El informe garantiza que Juniper lleva a cabo estos procesos cumpliendo o superando los requisitos establecidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Juniper sigue <strong>avanzando&nbsp;<\/strong>en la consecuci\u00f3n de&nbsp;<strong>objetivos&nbsp;<\/strong>y&nbsp;<strong>aportando&nbsp;<\/strong>un gran&nbsp;<strong>valor a\u00f1adido<\/strong>&nbsp;a sus Clientes gracias al&nbsp;<strong>esfuerzo&nbsp;<\/strong>y la&nbsp;<strong>coordinaci\u00f3n&nbsp;<\/strong>de sus m\u00e1s de 280 expertos en tecnolog\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de superar la certificaci\u00f3n&nbsp;SOC 2 Type I en la que se&nbsp;evaluaron 248 controles y tras la monitorizaci\u00f3n exhaustiva de la auditor\u00eda para verificar el&nbsp;cumplimiento&nbsp;de los&nbsp;procesos&nbsp;durante los \u00faltimos meses, Juniper ha completado con \u00e9xito la&nbsp;certificaci\u00f3n SOC 2 Type II. La obtenci\u00f3n de esta certificaci\u00f3n refuerza la promesa de Juniper de mantener los controles m\u00e1s estrictos, [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":22103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"categoria_divisiones":[],"class_list":["post-22107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juniper Blog | Juniper se certifica en SOC 2 Type II<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juniper Blog | Juniper se certifica en SOC 2 Type II\" \/>\n<meta property=\"og:description\" content=\"Despu\u00e9s de superar la certificaci\u00f3n&nbsp;SOC 2 Type I en la que se&nbsp;evaluaron 248 controles y tras la monitorizaci\u00f3n exhaustiva de la auditor\u00eda para verificar el&nbsp;cumplimiento&nbsp;de los&nbsp;procesos&nbsp;durante los \u00faltimos meses, Juniper ha completado con \u00e9xito la&nbsp;certificaci\u00f3n SOC 2 Type II. La obtenci\u00f3n de esta certificaci\u00f3n refuerza la promesa de Juniper de mantener los controles m\u00e1s estrictos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/\" \/>\n<meta property=\"og:site_name\" content=\"Juniper\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-31T09:52:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-08T12:56:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/08\/SOC_2_new.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marketingjuniper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marketingjuniper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/\"},\"author\":{\"name\":\"marketingjuniper\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#\\\/schema\\\/person\\\/6a217697a9fb79ac4dbcaf011ddba0a1\"},\"headline\":\"Juniper se certifica en SOC 2 Type II\",\"datePublished\":\"2022-08-31T09:52:27+00:00\",\"dateModified\":\"2025-05-08T12:56:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/\"},\"wordCount\":215,\"publisher\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/SOC_2_new.jpg\",\"articleSection\":[\"News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/\",\"name\":\"Juniper Blog | Juniper se certifica en SOC 2 Type II\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/SOC_2_new.jpg\",\"datePublished\":\"2022-08-31T09:52:27+00:00\",\"dateModified\":\"2025-05-08T12:56:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/SOC_2_new.jpg\",\"contentUrl\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/SOC_2_new.jpg\",\"width\":1440,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/juniper-becomes-soc-2-type-ii-certified\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juniper se certifica en SOC 2 Type II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/\",\"name\":\"https:\\\/\\\/ejuniper.com\\\/\",\"description\":\"Redefining Travel with Innovative Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#organization\",\"name\":\"Juniper Travel Technology\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/juniper-2-1.svg\",\"contentUrl\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/juniper-2-1.svg\",\"width\":48,\"height\":48,\"caption\":\"Juniper Travel Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/juniper\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/#\\\/schema\\\/person\\\/6a217697a9fb79ac4dbcaf011ddba0a1\",\"name\":\"marketingjuniper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b2bbe66c72e40b82c87360f761a3ea9672baa59b4f9dd067a1712d62124d8c3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b2bbe66c72e40b82c87360f761a3ea9672baa59b4f9dd067a1712d62124d8c3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4b2bbe66c72e40b82c87360f761a3ea9672baa59b4f9dd067a1712d62124d8c3?s=96&d=mm&r=g\",\"caption\":\"marketingjuniper\"},\"url\":\"https:\\\/\\\/ejuniper.com\\\/es\\\/blog\\\/author\\\/marketingjuniper\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juniper Blog | Juniper se certifica en SOC 2 Type II","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/","og_locale":"es_ES","og_type":"article","og_title":"Juniper Blog | Juniper se certifica en SOC 2 Type II","og_description":"Despu\u00e9s de superar la certificaci\u00f3n&nbsp;SOC 2 Type I en la que se&nbsp;evaluaron 248 controles y tras la monitorizaci\u00f3n exhaustiva de la auditor\u00eda para verificar el&nbsp;cumplimiento&nbsp;de los&nbsp;procesos&nbsp;durante los \u00faltimos meses, Juniper ha completado con \u00e9xito la&nbsp;certificaci\u00f3n SOC 2 Type II. La obtenci\u00f3n de esta certificaci\u00f3n refuerza la promesa de Juniper de mantener los controles m\u00e1s estrictos, [&hellip;]","og_url":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/","og_site_name":"Juniper","article_published_time":"2022-08-31T09:52:27+00:00","article_modified_time":"2025-05-08T12:56:21+00:00","og_image":[{"width":1440,"height":466,"url":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/08\/SOC_2_new.jpg","type":"image\/jpeg"}],"author":"marketingjuniper","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"marketingjuniper","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/#article","isPartOf":{"@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/"},"author":{"name":"marketingjuniper","@id":"https:\/\/ejuniper.com\/es\/#\/schema\/person\/6a217697a9fb79ac4dbcaf011ddba0a1"},"headline":"Juniper se certifica en SOC 2 Type II","datePublished":"2022-08-31T09:52:27+00:00","dateModified":"2025-05-08T12:56:21+00:00","mainEntityOfPage":{"@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/"},"wordCount":215,"publisher":{"@id":"https:\/\/ejuniper.com\/es\/#organization"},"image":{"@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/#primaryimage"},"thumbnailUrl":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/08\/SOC_2_new.jpg","articleSection":["News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/","url":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/","name":"Juniper Blog | Juniper se certifica en SOC 2 Type II","isPartOf":{"@id":"https:\/\/ejuniper.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/#primaryimage"},"image":{"@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/#primaryimage"},"thumbnailUrl":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/08\/SOC_2_new.jpg","datePublished":"2022-08-31T09:52:27+00:00","dateModified":"2025-05-08T12:56:21+00:00","breadcrumb":{"@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/#primaryimage","url":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/08\/SOC_2_new.jpg","contentUrl":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/08\/SOC_2_new.jpg","width":1440,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/ejuniper.com\/es\/blog\/juniper-becomes-soc-2-type-ii-certified\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/ejuniper.com\/es\/"},{"@type":"ListItem","position":2,"name":"Juniper se certifica en SOC 2 Type II"}]},{"@type":"WebSite","@id":"https:\/\/ejuniper.com\/es\/#website","url":"https:\/\/ejuniper.com\/es\/","name":"https:\/\/ejuniper.com\/","description":"Redefining Travel with Innovative Technology","publisher":{"@id":"https:\/\/ejuniper.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ejuniper.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ejuniper.com\/es\/#organization","name":"Juniper Travel Technology","url":"https:\/\/ejuniper.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ejuniper.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ejuniper.com\/wp-content\/uploads\/2024\/11\/juniper-2-1.svg","contentUrl":"https:\/\/ejuniper.com\/wp-content\/uploads\/2024\/11\/juniper-2-1.svg","width":48,"height":48,"caption":"Juniper Travel Technology"},"image":{"@id":"https:\/\/ejuniper.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/juniper\/"]},{"@type":"Person","@id":"https:\/\/ejuniper.com\/es\/#\/schema\/person\/6a217697a9fb79ac4dbcaf011ddba0a1","name":"marketingjuniper","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4b2bbe66c72e40b82c87360f761a3ea9672baa59b4f9dd067a1712d62124d8c3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4b2bbe66c72e40b82c87360f761a3ea9672baa59b4f9dd067a1712d62124d8c3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4b2bbe66c72e40b82c87360f761a3ea9672baa59b4f9dd067a1712d62124d8c3?s=96&d=mm&r=g","caption":"marketingjuniper"},"url":"https:\/\/ejuniper.com\/es\/blog\/author\/marketingjuniper\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/posts\/22107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/comments?post=22107"}],"version-history":[{"count":0,"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/posts\/22107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/media\/22103"}],"wp:attachment":[{"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/media?parent=22107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/categories?post=22107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/tags?post=22107"},{"taxonomy":"categoria_divisiones","embeddable":true,"href":"https:\/\/ejuniper.com\/es\/wp-json\/wp\/v2\/categoria_divisiones?post=22107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}