{"id":49398,"date":"2024-08-30T10:11:46","date_gmt":"2024-08-30T08:11:46","guid":{"rendered":"https:\/\/ejuniper.com\/?post_type=clients&#038;p=49398"},"modified":"2024-08-30T10:11:46","modified_gmt":"2024-08-30T08:11:46","slug":"rakuten-travel-xchange","status":"publish","type":"clients","link":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/","title":{"rendered":"Rakuten Travel Xchange"},"content":{"rendered":"<p>Rakuten Travel Xchange is the hotel wholesale and travel technology division within the Rakuten group, a global powerhouse with deep roots in Asia and dominance in Japan.<\/p>\n","protected":false},"author":46,"featured_media":20754,"parent":0,"menu_order":0,"template":"","tipo-cliente-new":[2074],"plataforma-cliente-new":[2189],"class_list":["post-49398","clients","type-clients","status-publish","has-post-thumbnail","hentry","tipo-cliente-new-accommodation-providers","plataforma-cliente-new-juniper-hub"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Clients | Juniper Travel Technology<\/title>\n<meta name=\"description\" content=\"Check out the Juniper\u00b4s Clients list. Meet the travel agencies, tour operators, DMCs, and many more who trust our technology.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Clients | Juniper Travel Technology\" \/>\n<meta property=\"og:description\" content=\"Check out the Juniper\u00b4s Clients list. Meet the travel agencies, tour operators, DMCs, and many more who trust our technology.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/\" \/>\n<meta property=\"og:site_name\" content=\"Juniper Travel Technology\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/03\/RakutenTravelXchange.png\" \/>\n\t<meta property=\"og:image:width\" content=\"286\" \/>\n\t<meta property=\"og:image:height\" content=\"85\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/\",\"name\":\"Clients | Juniper Travel Technology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/RakutenTravelXchange.png\",\"datePublished\":\"2024-08-30T08:11:46+00:00\",\"description\":\"Check out the Juniper\u00b4s Clients list. Meet the travel agencies, tour operators, DMCs, and many more who trust our technology.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/RakutenTravelXchange.png\",\"contentUrl\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/RakutenTravelXchange.png\",\"width\":286,\"height\":85},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients\\\/rakuten-travel-xchange\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Clientes\",\"item\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/clients-archive\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rakuten Travel Xchange\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/\",\"name\":\"https:\\\/\\\/ejuniper.com\\\/\",\"description\":\"Redefining Travel with Innovative Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/#organization\",\"name\":\"Juniper Travel Technology\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/juniper-2-1.svg\",\"contentUrl\":\"https:\\\/\\\/ejuniper.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/juniper-2-1.svg\",\"width\":48,\"height\":48,\"caption\":\"Juniper Travel Technology\"},\"image\":{\"@id\":\"https:\\\/\\\/ejuniper.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/juniper\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Clients | Juniper Travel Technology","description":"Check out the Juniper\u00b4s Clients list. Meet the travel agencies, tour operators, DMCs, and many more who trust our technology.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/","og_locale":"en_US","og_type":"article","og_title":"Clients | Juniper Travel Technology","og_description":"Check out the Juniper\u00b4s Clients list. Meet the travel agencies, tour operators, DMCs, and many more who trust our technology.","og_url":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/","og_site_name":"Juniper Travel Technology","og_image":[{"width":286,"height":85,"url":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/03\/RakutenTravelXchange.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/","url":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/","name":"Clients | Juniper Travel Technology","isPartOf":{"@id":"https:\/\/ejuniper.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/#primaryimage"},"image":{"@id":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/#primaryimage"},"thumbnailUrl":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/03\/RakutenTravelXchange.png","datePublished":"2024-08-30T08:11:46+00:00","description":"Check out the Juniper\u00b4s Clients list. Meet the travel agencies, tour operators, DMCs, and many more who trust our technology.","breadcrumb":{"@id":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/#primaryimage","url":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/03\/RakutenTravelXchange.png","contentUrl":"https:\/\/ejuniper.com\/wp-content\/uploads\/2022\/03\/RakutenTravelXchange.png","width":286,"height":85},{"@type":"BreadcrumbList","@id":"https:\/\/ejuniper.com\/en\/clients\/rakuten-travel-xchange\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ejuniper.com\/en\/"},{"@type":"ListItem","position":2,"name":"Clientes","item":"https:\/\/ejuniper.com\/en\/clients-archive\/"},{"@type":"ListItem","position":3,"name":"Rakuten Travel Xchange"}]},{"@type":"WebSite","@id":"https:\/\/ejuniper.com\/en\/#website","url":"https:\/\/ejuniper.com\/en\/","name":"https:\/\/ejuniper.com\/","description":"Redefining Travel with Innovative Technology","publisher":{"@id":"https:\/\/ejuniper.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ejuniper.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ejuniper.com\/en\/#organization","name":"Juniper Travel Technology","url":"https:\/\/ejuniper.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ejuniper.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ejuniper.com\/wp-content\/uploads\/2024\/11\/juniper-2-1.svg","contentUrl":"https:\/\/ejuniper.com\/wp-content\/uploads\/2024\/11\/juniper-2-1.svg","width":48,"height":48,"caption":"Juniper Travel Technology"},"image":{"@id":"https:\/\/ejuniper.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/juniper\/"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/clients\/49398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/clients"}],"about":[{"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/types\/clients"}],"author":[{"embeddable":true,"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/users\/46"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/media\/20754"}],"wp:attachment":[{"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/media?parent=49398"}],"wp:term":[{"taxonomy":"tipo-cliente-new","embeddable":true,"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/tipo-cliente-new?post=49398"},{"taxonomy":"plataforma-cliente-new","embeddable":true,"href":"https:\/\/ejuniper.com\/en\/wp-json\/wp\/v2\/plataforma-cliente-new?post=49398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}